{"id":280,"date":"2017-10-04T11:33:33","date_gmt":"2017-10-04T11:33:33","guid":{"rendered":"http:\/\/aifec.eu\/news\/?p=280"},"modified":"2017-11-24T14:09:26","modified_gmt":"2017-11-24T14:09:26","slug":"la-ultima-edicion-de-labelexpo-europa-ha-sido-la-mayor-de-la-historia-de-la-feria","status":"publish","type":"post","link":"https:\/\/aifec.eu\/news\/la-ultima-edicion-de-labelexpo-europa-ha-sido-la-mayor-de-la-historia-de-la-feria\/","title":{"rendered":"La \u00faltima edici\u00f3n de Labelexpo Europa ha sido la mayor de la historia de la feria"},"content":{"rendered":"<p>La feria Labelexpo Europe, celebrada en Bruselas del 25 al 28 de septiembre en Bruselas, ha sido todo un \u00e9xito de participaci\u00f3n. Ha ocupado nueve pabellones con un total de 38.000 metros cuadrados, en los que se han reunido 679 expositores, de los que 198 han sido nuevos.<\/p>\n<p>Tal como ha explicado la directora global de Labelexpo, Lisa Milburn, \u201cesta edici\u00f3n ha sido la que ha tenido mayor n\u00famero de m\u00e1quinas\u201d. \u201cEsto, a\u00f1adido a que se ha registrado gente de 139 pa\u00edses, con grandes delegaciones de Jap\u00f3n, India, Brasil, China e Ir\u00e1n, han hecho de este evento el mayor de la historia de la feria\u201d, a\u00f1adi\u00f3.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-large wp-image-281\" src=\"http:\/\/aifec.eu\/news\/wp-content\/uploads\/labelexpo4-1024x364.jpg\" alt=\"\" width=\"1020\" height=\"363\" srcset=\"https:\/\/aifec.eu\/news\/wp-content\/uploads\/labelexpo4-1024x364.jpg 1024w, https:\/\/aifec.eu\/news\/wp-content\/uploads\/labelexpo4-300x107.jpg 300w, https:\/\/aifec.eu\/news\/wp-content\/uploads\/labelexpo4-768x273.jpg 768w, https:\/\/aifec.eu\/news\/wp-content\/uploads\/labelexpo4-480x171.jpg 480w, https:\/\/aifec.eu\/news\/wp-content\/uploads\/labelexpo4-1405x500.jpg 1405w, https:\/\/aifec.eu\/news\/wp-content\/uploads\/labelexpo4.jpg 1798w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p>Durante los cuatro d\u00edas que ha durado la feria ha habido lanzamientos globales, charlas sobre tendencias del mercado, as\u00ed como la muestra de soluciones industriales por parte de los expositores, que cuentan con la maquinaria m\u00e1s puntera y los productos m\u00e1s novedosos.<\/p>\n<p>Andy Thomas, el director estrat\u00e9gico de Label &amp; Labeling del evento, ha dado algunos datos sobre las tendencias globales del mercado de las etiquetas. \u201cLa demanda mundial de etiquetas sensibles a la presi\u00f3n es del 40 por ciento, mientras que el pegamento h\u00famedo, que sigue siendo dominante en los pa\u00edses en desarrollo, es del 36 por ciento. Adem\u00e1s, hay crecimiento en sleeves, con una demanda global del 18 por ciento\u201d. Thomas a\u00f1adi\u00f3 tambi\u00e9n que el valor de mercado de las etiquetas impresas digitales \u201cha crecido hasta el 9,7 por ciento en Europa\u201d.<\/p>\n<p>La Asociaci\u00f3n Nacional de Fabricantes de Etiquetas en Continuo, ANFEC, promueve siempre la participaci\u00f3n de los asociados en este evento, el mayor del sector de las etiquetas. Entre las medidas que lleva a cabo est\u00e1 la <a href=\"http:\/\/aifec.eu\/news\/anfec-ofrece-subvenciones-para-ayudar-a-los-socios-a-participar-en-labelexpo-europe\/\" target=\"_blank\" rel=\"noopener noreferrer\">oferta de subvenciones<\/a> para ayudar a sus socios a financiar el viaje a Bruselas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La feria Labelexpo Europe, celebrada en Bruselas del 25 al 28 de septiembre en Bruselas, ha sido todo un \u00e9xito de participaci\u00f3n. Ha ocupado nueve pabellones con un total de 38.000 metros cuadrados, en los que se han reunido 679 expositores, de los que 198 han sido nuevos. Tal como ha explicado la directora global&hellip;<\/p>\n","protected":false},"author":1,"featured_media":282,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2,4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.0.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La \u00faltima edici\u00f3n de Labelexpo Europa ha sido la mayor de la historia de la feria - Aifec News<\/title>\n<link rel=\"canonical\" href=\"http:\/\/aifec.eu\/news\/la-ultima-edicion-de-labelexpo-europa-ha-sido-la-mayor-de-la-historia-de-la-feria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La \u00faltima edici\u00f3n de Labelexpo Europa ha sido la mayor de la historia de la feria - Aifec News\" \/>\n<meta property=\"og:description\" content=\"La feria Labelexpo Europe, celebrada en Bruselas del 25 al 28 de septiembre en Bruselas, ha sido todo un \u00e9xito de participaci\u00f3n. Ha ocupado nueve pabellones con un total de 38.000 metros cuadrados, en los que se han reunido 679 expositores, de los que 198 han sido nuevos. Tal como ha explicado la directora global&hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/aifec.eu\/news\/la-ultima-edicion-de-labelexpo-europa-ha-sido-la-mayor-de-la-historia-de-la-feria\/\" \/>\n<meta property=\"og:site_name\" content=\"Aifec News\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-04T11:33:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-24T14:09:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aifec.eu\/news\/wp-content\/uploads\/labelexpo1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1290\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\">\n\t<meta name=\"twitter:data1\" content=\"2 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aifec.eu\/news\/#website\",\"url\":\"https:\/\/aifec.eu\/news\/\",\"name\":\"Aifec News\",\"description\":\"El peri\\u00f3dico de la industria de etiquetas en continuo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/aifec.eu\/news\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/aifec.eu\/news\/la-ultima-edicion-de-labelexpo-europa-ha-sido-la-mayor-de-la-historia-de-la-feria\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/aifec.eu\/news\/wp-content\/uploads\/labelexpo1.jpg\",\"width\":1290,\"height\":640},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/aifec.eu\/news\/la-ultima-edicion-de-labelexpo-europa-ha-sido-la-mayor-de-la-historia-de-la-feria\/#webpage\",\"url\":\"http:\/\/aifec.eu\/news\/la-ultima-edicion-de-labelexpo-europa-ha-sido-la-mayor-de-la-historia-de-la-feria\/\",\"name\":\"La \\u00faltima edici\\u00f3n de Labelexpo Europa ha sido la mayor de la historia de la feria - Aifec News\",\"isPartOf\":{\"@id\":\"https:\/\/aifec.eu\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/aifec.eu\/news\/la-ultima-edicion-de-labelexpo-europa-ha-sido-la-mayor-de-la-historia-de-la-feria\/#primaryimage\"},\"datePublished\":\"2017-10-04T11:33:33+00:00\",\"dateModified\":\"2017-11-24T14:09:26+00:00\",\"author\":{\"@id\":\"https:\/\/aifec.eu\/news\/#\/schema\/person\/6d46059818a98ff411aa257d8037e371\"},\"breadcrumb\":{\"@id\":\"http:\/\/aifec.eu\/news\/la-ultima-edicion-de-labelexpo-europa-ha-sido-la-mayor-de-la-historia-de-la-feria\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/aifec.eu\/news\/la-ultima-edicion-de-labelexpo-europa-ha-sido-la-mayor-de-la-historia-de-la-feria\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/aifec.eu\/news\/la-ultima-edicion-de-labelexpo-europa-ha-sido-la-mayor-de-la-historia-de-la-feria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aifec.eu\/news\/\",\"url\":\"https:\/\/aifec.eu\/news\/\",\"name\":\"Portada\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/aifec.eu\/news\/la-ultima-edicion-de-labelexpo-europa-ha-sido-la-mayor-de-la-historia-de-la-feria\/\",\"url\":\"http:\/\/aifec.eu\/news\/la-ultima-edicion-de-labelexpo-europa-ha-sido-la-mayor-de-la-historia-de-la-feria\/\",\"name\":\"La \\u00faltima edici\\u00f3n de Labelexpo Europa ha sido la mayor de la historia de la feria\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/aifec.eu\/news\/#\/schema\/person\/6d46059818a98ff411aa257d8037e371\",\"name\":\"anfec\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/aifec.eu\/news\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fdb5d7427052ec840dd8b6e2cf4db678?s=96&d=mm&r=g\",\"caption\":\"anfec\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/posts\/280"}],"collection":[{"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/comments?post=280"}],"version-history":[{"count":1,"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/posts\/280\/revisions"}],"predecessor-version":[{"id":283,"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/posts\/280\/revisions\/283"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/media\/282"}],"wp:attachment":[{"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/media?parent=280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/categories?post=280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/tags?post=280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}