{"id":2430,"date":"2026-03-26T09:43:53","date_gmt":"2026-03-26T09:43:53","guid":{"rendered":"https:\/\/aifec.eu\/news\/?p=2430"},"modified":"2026-03-26T09:43:55","modified_gmt":"2026-03-26T09:43:55","slug":"biolid-sostenible","status":"publish","type":"post","link":"https:\/\/aifec.eu\/news\/biolid-sostenible\/","title":{"rendered":"BIOLID refuerza su apuesta por la sostenibilidad con la instalaci\u00f3n de una planta solar fotovoltaica que mejorar\u00e1 su eficiencia"},"content":{"rendered":"\n<p>En BIOLID, socios fabricantes de AIFEC, entienden la sostenibilidad como un eje estrat\u00e9gico de su modelo industrial. Por ello, el Plan Estrat\u00e9gico 2023\u20132028 incorpora de forma transversal la eficiencia energ\u00e9tica, la reducci\u00f3n del impacto ambiental y la innovaci\u00f3n responsable como palancas de competitividad y crecimiento.<\/p>\n\n\n\n<p>En este contexto, ha dado un nuevo paso adelante con la implantaci\u00f3n de una instalaci\u00f3n de autoconsumo solar con bater\u00edas en nuestra planta productiva, consolidando un modelo industrial m\u00e1s eficiente, resiliente y alineado con los criterios ESG.<\/p>\n\n\n\n<p>Esta iniciativa se enmarca, adem\u00e1s, en los programas de Transici\u00f3n Verde y de Transici\u00f3n Energ\u00e9tica de la Diputaci\u00f3n Foral de Bizkaia y del Ente Vasco de Energ\u00eda, as\u00ed como en el programa HAZITEK del Gobierno Vasco, junto con otros proyectos que forman parte de la pol\u00edtica de Responsabilidad Social Corporativa.<\/p>\n\n\n\n<p><strong>Instalaci\u00f3n fotovoltaica: energ\u00eda limpia al servicio de nuestra industria<\/strong><\/p>\n\n\n\n<p>El proyecto fotovoltaico, desarrollado por&nbsp;<strong>GREENKW y TSG<\/strong>, ha supuesto la instalaci\u00f3n de una planta solar de 225,74 kWp que cuenta con 447 paneles sobre la totalidad de la cubierta de la f\u00e1brica. A este proyecto ha a\u00f1adido un sistema de bater\u00edas de 92 kWh, dando un salto cualitativo hacia una mayor autonom\u00eda energ\u00e9tica.<\/p>\n\n\n\n<p>Gracias a esta instalaci\u00f3n, BIOLID puede:<\/p>\n\n\n\n<ul><li>Optimizar el consumo el\u00e9ctrico en horario productivo<\/li><li>Generar un ahorro directo en costes energ\u00e9ticos<\/li><li>Reducir la dependencia de la red el\u00e9ctrica<\/li><li>Almacenar excedentes solares para su uso fuera de las horas de producci\u00f3n<\/li><li>Disminuir de forma significativa la huella de carbono<\/li><li>Reforzar su competitividad en mercados cada vez m\u00e1s exigentes<\/li><\/ul>\n\n\n\n<p>Este proyecto ha supuesto una inversi\u00f3n superior a 200.000 \u20ac, con una amortizaci\u00f3n estimada inferior a dos a\u00f1os y un beneficio neto acumulado superior a 900.000 \u20ac durante la vida \u00fatil del sistema, consolid\u00e1ndose como una inversi\u00f3n estrat\u00e9gica, rentable y sostenible.<\/p>\n\n\n\n<p><strong>Una hoja de ruta clara hacia la sostenibilidad industrial<\/strong><\/p>\n\n\n\n<p>La instalaci\u00f3n fotovoltaica se suma a otros hitos que BIOLID ha ido alcanzando dentro de su&nbsp;<strong>Plan Estrat\u00e9gico 2023\u20132028<\/strong>:<\/p>\n\n\n\n<p><strong>2023 \u2013 Sustituci\u00f3n de l\u00e1mparas de secado UV por tecnolog\u00eda UV LED<\/strong><\/p>\n\n\n\n<p>En 2023 realiz\u00f3 una inversi\u00f3n de 200.000 \u20ac para sustituir las l\u00e1mparas de secado UV tradicionales por tecnolog\u00eda UV LED, uno de los cambios con mayor impacto ambiental en el sector de las artes gr\u00e1ficas.<\/p>\n\n\n\n<p>Con esta actuaci\u00f3n ha logrado:<\/p>\n\n\n\n<ul><li>Eliminar la generaci\u00f3n de ozono<\/li><li>Reducir de forma sustancial el consumo el\u00e9ctrico<\/li><li>Mejorar las condiciones de seguridad y salud laboral<\/li><\/ul>\n\n\n\n<p>Todo ello alineando su proceso productivo con criterios ESG y con una gesti\u00f3n m\u00e1s responsable y eficiente de los recursos.<\/p>\n\n\n\n<p><strong>2024 \u2013 Gesti\u00f3n avanzada de residuos de papel Lundberg<\/strong><\/p>\n\n\n\n<p>En 2024 BIOLID apost\u00f3 por mejorar la eficiencia en la gesti\u00f3n de su principal residuo, el papel. Incorpor\u00f3 un sistema de extracci\u00f3n y compactaci\u00f3n en sus cuatro m\u00e1quinas de mayor volumen, con una inversi\u00f3n de 120.000 \u20ac.<\/p>\n\n\n\n<p>Esta actuaci\u00f3n ha permitido:<\/p>\n\n\n\n<ul><li>Reducir de forma notable el volumen de residuo<\/li><li>Mejorar las condiciones laborales, disminuyendo el polvo en suspensi\u00f3n<\/li><li>Incrementar la productividad<\/li><li>Reducir la huella de carbono al eliminar desplazamientos innecesarios al vertedero<\/li><\/ul>\n\n\n\n<p>El objetivo de BIOLID es culminar este proyecto en&nbsp;<strong>2027<\/strong>, extendiendo el sistema a toda la planta. De forma paralela, puso en marcha el proyecto&nbsp;<strong>INFINITY<\/strong>, mediante el cual recoge y recicla el residuo de sus etiquetas, avanzando hacia un modelo de econom\u00eda circular.<\/p>\n\n\n\n<p><strong>2028 &#8211; Mirando al futuro: compostabilidad y normativa europea<\/strong><\/p>\n\n\n\n<p>En BIOLID se tiene la mirada puesta en el futuro y en los retos que plantea el Reglamento Europeo de Envases y Residuos de Envases (PPWR). A partir del 12 de febrero de 2028, las etiquetas adhesivas aplicadas a frutas y hortalizas deber\u00e1n cumplir est\u00e1ndares de compostabilidad.<\/p>\n\n\n\n<p>El compromiso es anticiparse a esta normativa y desarrollar soluciones t\u00e9cnicas sostenibles que permitan cumplir con estos requisitos, garantizando al mismo tiempo&nbsp;<strong>precios competitivos<\/strong>&nbsp;que no alejen al consumidor de su cesta de la compra ni penalicen a la cadena agroalimentaria.<\/p>\n\n\n\n<p><strong>Compromiso firme con una industria m\u00e1s sostenible<\/strong><\/p>\n\n\n\n<p>Con todas estas iniciativas,&nbsp;<strong>BIOLID<\/strong>&nbsp;refuerza su compromiso con la&nbsp;<strong>eficiencia energ\u00e9tica, la sostenibilidad ambiental y la competitividad industrial<\/strong>, demostrando que la transici\u00f3n ecol\u00f3gica es compatible con la innovaci\u00f3n, la rentabilidad y el desarrollo industrial responsable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En BIOLID, socios fabricantes de AIFEC, entienden la sostenibilidad como un eje estrat\u00e9gico de su modelo industrial. Por ello, el Plan Estrat\u00e9gico 2023\u20132028 incorpora de forma transversal la eficiencia energ\u00e9tica, la reducci\u00f3n del impacto ambiental y la innovaci\u00f3n responsable como palancas de competitividad y crecimiento. En este contexto, ha dado un nuevo paso adelante con&hellip;<\/p>\n","protected":false},"author":1,"featured_media":2431,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,10],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.0.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BIOLID refuerza su apuesta por la sostenibilidad con la instalaci\u00f3n de una planta solar fotovoltaica que mejorar\u00e1 su eficiencia - Aifec News<\/title>\n<meta name=\"description\" content=\"BIOLID apuesta por la sostenibilidad con la instalaci\u00f3n de una planta solar fotovoltaica, adem\u00e1s de otros hitos.\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aifec.eu\/news\/biolid-sostenible\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BIOLID refuerza su apuesta por la sostenibilidad con la instalaci\u00f3n de una planta solar fotovoltaica que mejorar\u00e1 su eficiencia - Aifec News\" \/>\n<meta property=\"og:description\" content=\"BIOLID apuesta por la sostenibilidad con la instalaci\u00f3n de una planta solar fotovoltaica, adem\u00e1s de otros hitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aifec.eu\/news\/biolid-sostenible\/\" \/>\n<meta property=\"og:site_name\" content=\"Aifec News\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-26T09:43:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-26T09:43:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aifec.eu\/news\/wp-content\/uploads\/13.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\">\n\t<meta name=\"twitter:data1\" content=\"3 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aifec.eu\/news\/#website\",\"url\":\"https:\/\/aifec.eu\/news\/\",\"name\":\"Aifec News\",\"description\":\"El peri\\u00f3dico de la industria de etiquetas en continuo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/aifec.eu\/news\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/aifec.eu\/news\/biolid-sostenible\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/aifec.eu\/news\/wp-content\/uploads\/13.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aifec.eu\/news\/biolid-sostenible\/#webpage\",\"url\":\"https:\/\/aifec.eu\/news\/biolid-sostenible\/\",\"name\":\"BIOLID refuerza su apuesta por la sostenibilidad con la instalaci\\u00f3n de una planta solar fotovoltaica que mejorar\\u00e1 su eficiencia - Aifec News\",\"isPartOf\":{\"@id\":\"https:\/\/aifec.eu\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/aifec.eu\/news\/biolid-sostenible\/#primaryimage\"},\"datePublished\":\"2026-03-26T09:43:53+00:00\",\"dateModified\":\"2026-03-26T09:43:55+00:00\",\"author\":{\"@id\":\"https:\/\/aifec.eu\/news\/#\/schema\/person\/6d46059818a98ff411aa257d8037e371\"},\"description\":\"BIOLID apuesta por la sostenibilidad con la instalaci\\u00f3n de una planta solar fotovoltaica, adem\\u00e1s de otros hitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/aifec.eu\/news\/biolid-sostenible\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/aifec.eu\/news\/biolid-sostenible\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aifec.eu\/news\/biolid-sostenible\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aifec.eu\/news\/\",\"url\":\"https:\/\/aifec.eu\/news\/\",\"name\":\"Portada\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aifec.eu\/news\/biolid-sostenible\/\",\"url\":\"https:\/\/aifec.eu\/news\/biolid-sostenible\/\",\"name\":\"BIOLID refuerza su apuesta por la sostenibilidad con la instalaci\\u00f3n de una planta solar fotovoltaica que mejorar\\u00e1 su eficiencia\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/aifec.eu\/news\/#\/schema\/person\/6d46059818a98ff411aa257d8037e371\",\"name\":\"anfec\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/aifec.eu\/news\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fdb5d7427052ec840dd8b6e2cf4db678?s=96&d=mm&r=g\",\"caption\":\"anfec\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/posts\/2430"}],"collection":[{"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/comments?post=2430"}],"version-history":[{"count":1,"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/posts\/2430\/revisions"}],"predecessor-version":[{"id":2432,"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/posts\/2430\/revisions\/2432"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/media\/2431"}],"wp:attachment":[{"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/media?parent=2430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/categories?post=2430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/tags?post=2430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}