{"id":1692,"date":"2023-01-30T13:02:35","date_gmt":"2023-01-30T13:02:35","guid":{"rendered":"http:\/\/aifec.eu\/news\/?p=1692"},"modified":"2023-01-30T13:11:18","modified_gmt":"2023-01-30T13:11:18","slug":"tecnocut-vuelve-a-obtener-el-sello-pyme-innovadora","status":"publish","type":"post","link":"http:\/\/aifec.eu\/news\/tecnocut-vuelve-a-obtener-el-sello-pyme-innovadora\/","title":{"rendered":"Tecnocut vuelve a obtener el sello PYME Innovadora"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.tecnocut.com\/\">Tecnocut<\/a>&nbsp;, nuestros socios proveedores de AIFEC, celebran su 30 aniversario y la obtenci\u00f3n del sello PYME Innovadora por segunda vez.&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>\u00bfPodr\u00eda presentarnos brevemente su empresa?<\/strong><\/p>\n\n\n\n<p>Tenocut es una empresa centrada en dar soluciones de ingenier\u00eda y maquinaria inteligente para la industria de la etiqueta y el converting. Su objetivo es ofrecer un servicio integral, basado en el asesoramiento personalizado y la ingenier\u00eda a medida. Tecnocut fue fundada en 1993 por lo que este a\u00f1o celebra su 30 aniversario.\u00a0El 2008 crearon el departamento de Innovaci\u00f3n + Desarrollo y se aumenta el portafolio de productos.\u00a0\u00a0En 2020 reciben por primera vez el sello PYME innovadora que es otorgado por el gobierno de Espa\u00f1a.\u00a0\u00a0<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9&nbsp;es&nbsp;el&nbsp;sello&nbsp;PYME&nbsp;INNOVADORA?<\/strong><\/p>\n\n\n\n<p>El sello PYME Innovadora es un reconocimiento otorgado por parte del Ministerio de&nbsp;Ciencia e Innovaci\u00f3n a las empresas cuya actividad se centra en I+D+i. La distinci\u00f3n se&nbsp;cre\u00f3 en junio de 2014, con el objetivo de instaurar un sistema de discriminaci\u00f3n positiva&nbsp;entre las empresas que favoreciera a aquellas con mayor probabilidad de permanecer&nbsp;en&nbsp;el&nbsp;tiempo,&nbsp;crecer&nbsp;y&nbsp;ser&nbsp;competitivas.<\/p>\n\n\n\n<p><em>\u201cObtener dos veces consecutivas el sello PYME INNOVADORA es un reconocimiento que demuestra nuestra dedicaci\u00f3n y compromiso de ofrecer tecnolog\u00eda de \u00faltima generaci\u00f3n a la industria en general y, especialmente, al sector de la etiqueta y el converting\u201d.\u00a0<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\">&nbsp;Franc&nbsp;Estrada,&nbsp;Chief&nbsp;Engineer&nbsp;Officer&nbsp;de&nbsp;Tecnocut.<\/p>\n\n\n\n<p><strong>\u00bfC\u00f3mo hab\u00e9is vuelto a conseguir el sello PYME por segunda vez?<\/strong><\/p>\n\n\n\n<p>Gracias al trabajo de un equipo multidisciplinar, formado por un departamento de ingenier\u00eda y una planta de producci\u00f3n propia, Tecnocut puede seguir apostando por la innovaci\u00f3n y la mejora continua. Con la renovaci\u00f3n del sello PYME Innovadora, Tecnocut se ha convertido en miembro del destacado y reducido grupo de empresas espa\u00f1olas, a las que se ha otorgado el m\u00e9rito en m\u00e1s de una ocasi\u00f3n. El sello se ha concedido por la naturaleza innovadora de la empresa y su participaci\u00f3n en numerosos proyectos pioneros en los \u00faltimos a\u00f1os.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tecnocut&nbsp;, nuestros socios proveedores de AIFEC, celebran su 30 aniversario y la obtenci\u00f3n del sello PYME Innovadora por segunda vez.&nbsp;&nbsp; \u00bfPodr\u00eda presentarnos brevemente su empresa? Tenocut es una empresa centrada en dar soluciones de ingenier\u00eda y maquinaria inteligente para la industria de la etiqueta y el converting. Su objetivo es ofrecer un servicio integral, basado&hellip;<\/p>\n","protected":false},"author":1,"featured_media":1693,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,2,10],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.0.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tecnocut vuelve a obtener el sello PYME Innovadora - Aifec News<\/title>\n<meta name=\"description\" content=\"Tecnocut , nuestros socios proveedores de AIFEC, celebran su 30 aniversario y la obtenci\u00f3n del sello PYME Innovadora por segunda vez.\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aifec.eu\/news\/tecnocut-vuelve-a-obtener-el-sello-pyme-innovadora\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tecnocut vuelve a obtener el sello PYME Innovadora - Aifec News\" \/>\n<meta property=\"og:description\" content=\"Tecnocut , nuestros socios proveedores de AIFEC, celebran su 30 aniversario y la obtenci\u00f3n del sello PYME Innovadora por segunda vez.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aifec.eu\/news\/tecnocut-vuelve-a-obtener-el-sello-pyme-innovadora\/\" \/>\n<meta property=\"og:site_name\" content=\"Aifec News\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-30T13:02:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-30T13:11:18+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/aifec.eu\/news\/wp-content\/uploads\/portada.png\" \/>\n\t<meta property=\"og:image:width\" content=\"727\" \/>\n\t<meta property=\"og:image:height\" content=\"545\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\">\n\t<meta name=\"twitter:data1\" content=\"2 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aifec.eu\/news\/#website\",\"url\":\"https:\/\/aifec.eu\/news\/\",\"name\":\"Aifec News\",\"description\":\"El peri\\u00f3dico de la industria de etiquetas en continuo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/aifec.eu\/news\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/aifec.eu\/news\/tecnocut-vuelve-a-obtener-el-sello-pyme-innovadora\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"http:\/\/aifec.eu\/news\/wp-content\/uploads\/portada.png\",\"width\":727,\"height\":545,\"caption\":\"Tecnocut\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aifec.eu\/news\/tecnocut-vuelve-a-obtener-el-sello-pyme-innovadora\/#webpage\",\"url\":\"https:\/\/aifec.eu\/news\/tecnocut-vuelve-a-obtener-el-sello-pyme-innovadora\/\",\"name\":\"Tecnocut vuelve a obtener el sello PYME Innovadora - Aifec News\",\"isPartOf\":{\"@id\":\"https:\/\/aifec.eu\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/aifec.eu\/news\/tecnocut-vuelve-a-obtener-el-sello-pyme-innovadora\/#primaryimage\"},\"datePublished\":\"2023-01-30T13:02:35+00:00\",\"dateModified\":\"2023-01-30T13:11:18+00:00\",\"author\":{\"@id\":\"https:\/\/aifec.eu\/news\/#\/schema\/person\/6d46059818a98ff411aa257d8037e371\"},\"description\":\"Tecnocut , nuestros socios proveedores de AIFEC, celebran su 30 aniversario y la obtenci\\u00f3n del sello PYME Innovadora por segunda vez.\",\"breadcrumb\":{\"@id\":\"https:\/\/aifec.eu\/news\/tecnocut-vuelve-a-obtener-el-sello-pyme-innovadora\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/aifec.eu\/news\/tecnocut-vuelve-a-obtener-el-sello-pyme-innovadora\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aifec.eu\/news\/tecnocut-vuelve-a-obtener-el-sello-pyme-innovadora\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aifec.eu\/news\/\",\"url\":\"https:\/\/aifec.eu\/news\/\",\"name\":\"Portada\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aifec.eu\/news\/tecnocut-vuelve-a-obtener-el-sello-pyme-innovadora\/\",\"url\":\"https:\/\/aifec.eu\/news\/tecnocut-vuelve-a-obtener-el-sello-pyme-innovadora\/\",\"name\":\"Tecnocut vuelve a obtener el sello PYME Innovadora\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/aifec.eu\/news\/#\/schema\/person\/6d46059818a98ff411aa257d8037e371\",\"name\":\"anfec\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/aifec.eu\/news\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/fdb5d7427052ec840dd8b6e2cf4db678?s=96&d=mm&r=g\",\"caption\":\"anfec\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/posts\/1692"}],"collection":[{"href":"http:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/comments?post=1692"}],"version-history":[{"count":6,"href":"http:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/posts\/1692\/revisions"}],"predecessor-version":[{"id":1700,"href":"http:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/posts\/1692\/revisions\/1700"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/media\/1693"}],"wp:attachment":[{"href":"http:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/media?parent=1692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/categories?post=1692"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/aifec.eu\/news\/wp-json\/wp\/v2\/tags?post=1692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}